{"id":604,"date":"2022-01-06T12:28:52","date_gmt":"2022-01-06T12:28:52","guid":{"rendered":"https:\/\/blockart-book-author.sites.qsandbox.com\/?page_id=604"},"modified":"2023-04-13T03:38:18","modified_gmt":"2023-04-13T03:38:18","slug":"contact","status":"publish","type":"page","link":"https:\/\/lettilustcraft.com\/index.php\/contact\/","title":{"rendered":"CONTACT"},"content":{"rendered":"<div class=\"blockart-section blockart-section-e63b78d3\"><div class=\"blockart-container\"><div class=\"blockart-section-inner\"><div class=\"blockart-column blockart-column-e0602915\"><div class=\"blockart-column-inner\"><div class=\"blockart-image blockart-image-16570769\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"wp-image-1945\" src=\"https:\/\/i0.wp.com\/lettilustcraft.com\/wp-content\/uploads\/2023\/04\/Untitled-design-e1681355809489.png?resize=475%2C360&#038;ssl=1\" alt=\"\" height=\"360\" width=\"475\" srcset=\"https:\/\/i0.wp.com\/lettilustcraft.com\/wp-content\/uploads\/2023\/04\/Untitled-design-e1681355809489.png?w=475&amp;ssl=1 475w, https:\/\/i0.wp.com\/lettilustcraft.com\/wp-content\/uploads\/2023\/04\/Untitled-design-e1681355809489.png?resize=300%2C227&amp;ssl=1 300w\" sizes=\"auto, (max-width: 475px) 100vw, 475px\" \/><\/div>\n\n<p class=\"blockart-paragraph blockart-paragraph-6432d60f\">Mail<\/p>\n\n<p class=\"blockart-paragraph blockart-paragraph-99b15a65\">info@lettilustcraft.com<\/p><\/div><\/div><\/div><\/div><\/div><div class=\"blockart-section blockart-section-d6cc7658\"><div class=\"blockart-overlay\"><\/div><div class=\"blockart-container\"><div class=\"blockart-section-inner\"><div class=\"blockart-column blockart-column-b51aa310\"><div class=\"blockart-column-inner\"><\/div><\/div>\n\n<div class=\"blockart-column blockart-column-8de4696d\"><div class=\"blockart-column-inner\"><div class=\"blockart-column blockart-column-767a2244\"><div class=\"blockart-column-inner\"><p class=\"blockart-paragraph blockart-paragraph-64b60d7b\">GET IN TOUCH<\/p>\n\n<div class=\"everest-forms\"><div class=\"evf-container default\" id=\"evf-648\"><form id=\"evf-form-648\" class=\"everest-form\" data-formid=\"648\" data-ajax_submission=\"0\" data-keyboard_friendly_form=\"0\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/604\"><div class=\"evf-field-container\"><input type=\"hidden\" id=\"_wpnonce648\" name=\"_wpnonce648\" value=\"a514126a91\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/index.php\/wp-json\/wp\/v2\/pages\/604\" \/><div class=\"evf-frontend-row\" data-row=\"row_1\" conditional_rules=\"[]\"><div class=\"evf-frontend-grid evf-grid-1\" data-grid=\"grid_1\"><div id=\"evf-648-field_fullname-container\" class=\"evf-field evf-field-text form-row\" data-field-id=\"fullname\"><label class=\"evf-field-label evf-label-hide\" for=\"evf-648-field_fullname\"><span class=\"evf-label\">Name<\/span> <\/label><input type=\"text\" id=\"evf-648-field_fullname\" class=\"input-text\" name=\"everest_forms[form_fields][fullname]\" placeholder=\"Name\" ><\/div><div id=\"evf-648-field_email-container\" class=\"evf-field evf-field-email form-row validate-email\" data-field-id=\"email\"><label class=\"evf-field-label evf-label-hide\" for=\"evf-648-field_email\"><span class=\"evf-label\">Online Username<\/span> <\/label><input type=\"email\" id=\"evf-648-field_email\" class=\"input-text\" name=\"everest_forms[form_fields][email]\" placeholder=\"Online Username (optional)\"  ><\/div><div id=\"evf-648-field_bPiL6a3R3X-1-container\" class=\"evf-field evf-field-text form-row\" data-field-id=\"bPiL6a3R3X-1\"><label class=\"evf-field-label evf-label-hide\" for=\"evf-648-field_bPiL6a3R3X-1\"><span class=\"evf-label\">Email<\/span> <\/label><input type=\"text\" id=\"evf-648-field_bPiL6a3R3X-1\" class=\"input-text\" name=\"everest_forms[form_fields][bPiL6a3R3X-1]\" placeholder=\"Email\" ><\/div><div id=\"evf-648-field_message-container\" class=\"evf-field evf-field-textarea form-row\" data-field-id=\"message\"><label class=\"evf-field-label evf-label-hide\" for=\"evf-648-field_message\"><span class=\"evf-label\">Message<\/span> <\/label><textarea id=\"evf-648-field_message\" class=\"input-text\" name=\"everest_forms[form_fields][message]\" placeholder=\"Write something smutty.\"  ><\/textarea><\/div><\/div><\/div><\/div><div class=\"evf-honeypot-container evf-field-hp\"><label for=\"evf-648-field-hp\" class=\"evf-field-label\">Name<\/label><input type=\"text\" name=\"everest_forms[hp]\" id=\"evf-648-field-hp\" class=\"input-text\"><\/div><div class=\"evf-submit-container \" ><input type=\"hidden\" name=\"everest_forms[id]\" value=\"648\"><input type=\"hidden\" name=\"everest_forms[author]\" value=\"1\"><button type='submit' name='everest_forms[submit]' class='everest-forms-submit-button button evf-submit ' id='evf-submit-648' value='evf-submit' data-process-text=\"Processing\u2026\" conditional_rules='&quot;&quot;' conditional_id='evf-submit-648'  id=\"evf-submit-648\" aria-live=\"assertive\">Submit<\/button><\/div><\/form><\/div><!-- .evf-container --><\/div><\/div><\/div><\/div><\/div>\n\n<div class=\"blockart-column blockart-column-a1e66a26\"><div class=\"blockart-column-inner\"><\/div><\/div><\/div><\/div><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/pagebuilder.php","meta":{"zakra_sidebar_layout":"stretched","zakra_remove_content_margin":false,"zakra_sidebar":"customizer","zakra_transparent_header":"customizer","zakra_logo":0,"zakra_main_header_style":"default","zakra_menu_item_color":"","zakra_menu_item_hover_color":"","zakra_menu_item_active_color":"","zakra_menu_active_style":"","zakra_page_header":true,"footnotes":""},"class_list":["post-604","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/lettilustcraft.com\/index.php\/wp-json\/wp\/v2\/pages\/604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lettilustcraft.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lettilustcraft.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lettilustcraft.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lettilustcraft.com\/index.php\/wp-json\/wp\/v2\/comments?post=604"}],"version-history":[{"count":15,"href":"https:\/\/lettilustcraft.com\/index.php\/wp-json\/wp\/v2\/pages\/604\/revisions"}],"predecessor-version":[{"id":1952,"href":"https:\/\/lettilustcraft.com\/index.php\/wp-json\/wp\/v2\/pages\/604\/revisions\/1952"}],"wp:attachment":[{"href":"https:\/\/lettilustcraft.com\/index.php\/wp-json\/wp\/v2\/media?parent=604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}